{"id":2,"count":1,"description":"","link":"https:\/\/mpdevelopment.eu\/lt\/category\/3d-illustrations\/","name":"3D Illustrations","slug":"3d-illustrations","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/mpdevelopment.eu\/lt\/wp-json\/wp\/v2\/categories\/2","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mpdevelopment.eu\/lt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/mpdevelopment.eu\/lt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/mpdevelopment.eu\/lt\/wp-json\/wp\/v2\/posts?categories=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}